{"id":154042,"date":"2022-09-23T13:50:58","date_gmt":"2022-09-23T11:50:58","guid":{"rendered":"https:\/\/autobaak.nl\/?page_id=154042"},"modified":"2022-09-23T13:50:58","modified_gmt":"2022-09-23T11:50:58","slug":"reifendruck-renault-laguna","status":"publish","type":"page","link":"https:\/\/autobaak.nl\/de\/bandenspanning-renault-laguna\/","title":{"rendered":"Reifendruck Renault Laguna"},"content":{"rendered":"<p>Der richtige Reifendruck f\u00fcr Ihren Renault Laguna? Auf dieser Seite finden Sie eine \u00dcbersicht aller Modelle von Renault Laguna und die dazugeh\u00f6rigen Reifendr\u00fccke:<\/p>\n<table class=\"table table-striped table-bordered table-hover table-responsive\">\n<thead class=\"thead-dark\">\n<tr>\n<th>Antrieb<\/th>\n<th>Gr\u00f6\u00dfe des Reifens<\/th>\n<th>Reifendruck Vorderr\u00e4der<\/th>\n<th>Reifendruck am Hinterrad<\/th>\n<th>Frontlader<\/th>\n<th>Laden Sie die R\u00fcckseite<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td data-title=\"Aandrijving\"><strong>1.6<\/strong><\/td>\n<td data-title=\"Bandenmaat\">195 60 R16 89H<\/td>\n<td data-title=\"Bandenspanning voorwielen\">2.3<\/td>\n<td data-title=\"Bandenspanning achterwielen\">2.1<\/td>\n<td data-title=\"Voorkant beladen\">2.5<\/td>\n<td data-title=\"Achterkant beladen\">2.1<\/td>\n<\/tr>\n<tr>\n<td data-title=\"Aandrijving\"><strong>1.6<\/strong><\/td>\n<td data-title=\"Bandenmaat\">205 60 R16 92H<\/td>\n<td data-title=\"Bandenspanning voorwielen\">2.3<\/td>\n<td data-title=\"Bandenspanning achterwielen\">2.1<\/td>\n<td data-title=\"Voorkant beladen\">2.5<\/td>\n<td data-title=\"Achterkant beladen\">2.1<\/td>\n<\/tr>\n<tr>\n<td data-title=\"Aandrijving\"><strong>1.6<\/strong><\/td>\n<td data-title=\"Bandenmaat\">215 50 R17 95W XL<\/td>\n<td data-title=\"Bandenspanning voorwielen\">2.2<\/td>\n<td data-title=\"Bandenspanning achterwielen\">2.0<\/td>\n<td data-title=\"Voorkant beladen\">2.3<\/td>\n<td data-title=\"Achterkant beladen\">2.0<\/td>\n<\/tr>\n<tr>\n<td data-title=\"Aandrijving\"><strong>2.0<\/strong><\/td>\n<td data-title=\"Bandenmaat\">205 60 R16 92V<\/td>\n<td data-title=\"Bandenspanning voorwielen\">2.6<\/td>\n<td data-title=\"Bandenspanning achterwielen\">2.2<\/td>\n<td data-title=\"Voorkant beladen\">2.8<\/td>\n<td data-title=\"Achterkant beladen\">2.3<\/td>\n<\/tr>\n<tr>\n<td data-title=\"Aandrijving\"><strong>2.0<\/strong><\/td>\n<td data-title=\"Bandenmaat\">215 50 R17 95W XL<\/td>\n<td data-title=\"Bandenspanning voorwielen\">2.6<\/td>\n<td data-title=\"Bandenspanning achterwielen\">2.2<\/td>\n<td data-title=\"Voorkant beladen\">2.8<\/td>\n<td data-title=\"Achterkant beladen\">2.3<\/td>\n<\/tr>\n<tr>\n<td data-title=\"Aandrijving\"><strong>2.0<\/strong><\/td>\n<td data-title=\"Bandenmaat\">225 45 R18 95W XL<\/td>\n<td data-title=\"Bandenspanning voorwielen\">2.6<\/td>\n<td data-title=\"Bandenspanning achterwielen\">2.2<\/td>\n<td data-title=\"Voorkant beladen\">2.8<\/td>\n<td data-title=\"Achterkant beladen\">2.3<\/td>\n<\/tr>\n<tr>\n<td data-title=\"Aandrijving\"><strong>2,0 TCe<\/strong><\/td>\n<td data-title=\"Bandenmaat\">215 50 R17 95W XL<\/td>\n<td data-title=\"Bandenspanning voorwielen\">2.4<\/td>\n<td data-title=\"Bandenspanning achterwielen\">2.1<\/td>\n<td data-title=\"Voorkant beladen\">2.6<\/td>\n<td data-title=\"Achterkant beladen\">2.2<\/td>\n<\/tr>\n<tr>\n<td data-title=\"Aandrijving\"><strong>2,0 TCe<\/strong><\/td>\n<td data-title=\"Bandenmaat\">225 45 R18 95W XL<\/td>\n<td data-title=\"Bandenspanning voorwielen\">2.4<\/td>\n<td data-title=\"Bandenspanning achterwielen\">2.1<\/td>\n<td data-title=\"Voorkant beladen\">2.6<\/td>\n<td data-title=\"Achterkant beladen\">2.2<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>De juiste bandenspanning voor jouw Renault Laguna? Op deze pagina een overzicht van de Renault Laguna modellen en bijbehorende bandenspanning: Aandrijving Bandenmaat Bandenspanning voorwielen Bandenspanning achterwielen Voorkant beladen Achterkant beladen 1.6 195 60 R16 89H 2.3 2.1 2.5 2.1 1.6 205 60 R16 92H 2.3 2.1 2.5 2.1 1.6 215 50 R17 95W XL 2.2 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-154042","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bandenspanning Renault Laguna - Autobaak.nl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/autobaak.nl\/de\/reifendruck-renault-laguna\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bandenspanning Renault Laguna - Autobaak.nl\" \/>\n<meta property=\"og:description\" content=\"De juiste bandenspanning voor jouw Renault Laguna? Op deze pagina een overzicht van de Renault Laguna modellen en bijbehorende bandenspanning: Aandrijving Bandenmaat Bandenspanning voorwielen Bandenspanning achterwielen Voorkant beladen Achterkant beladen 1.6 195 60 R16 89H 2.3 2.1 2.5 2.1 1.6 205 60 R16 92H 2.3 2.1 2.5 2.1 1.6 215 50 R17 95W XL 2.2 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autobaak.nl\/de\/reifendruck-renault-laguna\/\" \/>\n<meta property=\"og:site_name\" content=\"Autobaak.nl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autobaak.nl\\\/bandenspanning-renault-laguna\\\/\",\"url\":\"https:\\\/\\\/autobaak.nl\\\/bandenspanning-renault-laguna\\\/\",\"name\":\"Bandenspanning Renault Laguna - Autobaak.nl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autobaak.nl\\\/#website\"},\"datePublished\":\"2022-09-23T11:50:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autobaak.nl\\\/bandenspanning-renault-laguna\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autobaak.nl\\\/bandenspanning-renault-laguna\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autobaak.nl\\\/bandenspanning-renault-laguna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/autobaak.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bandenspanning Renault Laguna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autobaak.nl\\\/#website\",\"url\":\"https:\\\/\\\/autobaak.nl\\\/\",\"name\":\"Autobaak.nl\",\"description\":\"Cars &amp; Racing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autobaak.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reifendruck Renault Laguna - Autobaak.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/autobaak.nl\/de\/reifendruck-renault-laguna\/","og_locale":"de_DE","og_type":"article","og_title":"Bandenspanning Renault Laguna - Autobaak.nl","og_description":"De juiste bandenspanning voor jouw Renault Laguna? Op deze pagina een overzicht van de Renault Laguna modellen en bijbehorende bandenspanning: Aandrijving Bandenmaat Bandenspanning voorwielen Bandenspanning achterwielen Voorkant beladen Achterkant beladen 1.6 195 60 R16 89H 2.3 2.1 2.5 2.1 1.6 205 60 R16 92H 2.3 2.1 2.5 2.1 1.6 215 50 R17 95W XL 2.2 [&hellip;]","og_url":"https:\/\/autobaak.nl\/de\/reifendruck-renault-laguna\/","og_site_name":"Autobaak.nl","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autobaak.nl\/bandenspanning-renault-laguna\/","url":"https:\/\/autobaak.nl\/bandenspanning-renault-laguna\/","name":"Reifendruck Renault Laguna - Autobaak.de","isPartOf":{"@id":"https:\/\/autobaak.nl\/#website"},"datePublished":"2022-09-23T11:50:58+00:00","breadcrumb":{"@id":"https:\/\/autobaak.nl\/bandenspanning-renault-laguna\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autobaak.nl\/bandenspanning-renault-laguna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/autobaak.nl\/bandenspanning-renault-laguna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/autobaak.nl\/"},{"@type":"ListItem","position":2,"name":"Bandenspanning Renault Laguna"}]},{"@type":"WebSite","@id":"https:\/\/autobaak.nl\/#website","url":"https:\/\/autobaak.nl\/","name":"Autobook.de","description":"Autos &amp; Rennsport","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autobaak.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/autobaak.nl\/de\/wp-json\/wp\/v2\/pages\/154042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autobaak.nl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/autobaak.nl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/autobaak.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/autobaak.nl\/de\/wp-json\/wp\/v2\/comments?post=154042"}],"version-history":[{"count":0,"href":"https:\/\/autobaak.nl\/de\/wp-json\/wp\/v2\/pages\/154042\/revisions"}],"wp:attachment":[{"href":"https:\/\/autobaak.nl\/de\/wp-json\/wp\/v2\/media?parent=154042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}